{"id":1694,"date":"2022-10-27T12:08:38","date_gmt":"2022-10-27T10:08:38","guid":{"rendered":"https:\/\/www.fahrradstadt-pforzheim.de\/?p=1694"},"modified":"2022-10-27T17:56:02","modified_gmt":"2022-10-27T15:56:02","slug":"petition-nach-totgefahrenem-kind","status":"publish","type":"post","link":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/2022\/10\/27\/petition-nach-totgefahrenem-kind\/","title":{"rendered":"Petition nach totgefahrenem Kind"},"content":{"rendered":"\n<p>Im Stadtgebiet Tiergarten wurde ein Kind auf einem Skateboard von einem Paketzusteller \u00fcberfahren. Die Stadt plant dazu laut einem Artikel in der BNN vom 26.10.2022 folgendes:<\/p>\n\n\n\n<ul><li>Man wird einen Zaun aufstellen, damit die Kinder nicht mehr vom Spielplatz auf die Stra\u00dfe fahren k\u00f6nnen.<\/li><li>L\u00fccken in den Hecken, die den Spielplatz von der Stra\u00dfe trennen sollen geschlossen werden.<\/li><li>Hecken, die die Sicht auf die Stra\u00dfe zu verbessern.<\/li><\/ul>\n\n\n\n<p>Toll w\u00fcrden wir noch finden:<\/p>\n\n\n\n<ul><li>Schwellen auf der Fahrbahn, die die Geschwindigkeitsbegrenzung umzusetzen helfen.<\/li><li>Die Stra\u00dfe beim Spielplatz zur Spielstra\u00dfe zu machen.<\/li><li>Mehr Geschwindigkeitskontrollen.<\/li><\/ul>\n\n\n\n<p>Es sollte nicht sein, dass die Konsequenz aus solch tragischen Unf\u00e4llen regelm\u00e4ssig ist, dass nur die Kinder mehr eingez\u00e4unt werden und die Stadt lediglich noch autogerechter gemacht wird.<\/p>\n\n\n\n<p>Wer gemeinsam mit uns glaubt, dass die Stadt lebenswerter wird, wenn sie f\u00fcr unsere Kinder auch auf der Stra\u00dfe sicherer wird, der\/dem empfehlen wir folgende Online-Petition &#8222;f\u00fcr sichere Schulwege, Spielm\u00f6glichkeiten f\u00fcr Kinder und Menschen im Tiergarten\/Buckenberg PF&#8220;:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.openpetition.de\/petition\/argumente\/sichere-fusswege-schulwege-spielmoeglichkeiten-fuer-kinder-und-menschen-im-tiergarten-buckenberg-pf\">https:\/\/www.openpetition.de\/petition\/argumente\/sichere-fusswege-schulwege-spielmoeglichkeiten-fuer-kinder-und-menschen-im-tiergarten-buckenberg-pf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Stadtgebiet Tiergarten wurde ein Kind auf einem Skateboard von einem Paketzusteller \u00fcberfahren. Die Stadt plant dazu laut einem Artikel in der BNN vom 26.10.2022 folgendes: Man wird einen Zaun aufstellen, damit die Kinder nicht mehr vom Spielplatz auf die Stra\u00dfe fahren k\u00f6nnen. L\u00fccken in den Hecken, die den Spielplatz von der Stra\u00dfe trennen sollen [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1423,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[23,85,69],"_links":{"self":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1694"}],"collection":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=1694"}],"version-history":[{"count":4,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1694\/revisions"}],"predecessor-version":[{"id":1699,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1694\/revisions\/1699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media\/1423"}],"wp:attachment":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=1694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=1694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=1694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}