{"id":362,"date":"2020-10-24T23:25:02","date_gmt":"2020-10-24T21:25:02","guid":{"rendered":"https:\/\/www.fahrradstadt-pforzheim.de\/?p=362"},"modified":"2020-10-24T23:25:03","modified_gmt":"2020-10-24T21:25:03","slug":"wie-wollen-wir-mobil-sein","status":"publish","type":"post","link":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/2020\/10\/24\/wie-wollen-wir-mobil-sein\/","title":{"rendered":"Wie wollen wir mobil sein?"},"content":{"rendered":"\n<p>Die Stadt Pforzheim m\u00f6chte den Rahmen f\u00fcr die Mobilit\u00e4tsentwicklung der n\u00e4chsten Jahre neu definieren und daf\u00fcr gemeinsam mit einem Fachb\u00fcro f\u00fcr Pforzheim einen sogenannten <strong>Integrierten Mobilit\u00e4tsentwicklungsplan<\/strong> (kurz: <strong>IMEP<\/strong>) erstellen.<\/p>\n\n\n\n<p>In einer <a rel=\"noreferrer noopener\" href=\"https:\/\/www.pforzheim.de\/stadt\/aktuelles\/pressemeldungen\/s1\/article\/detail\/News\/pforzheim-mobil-startet-erste-beteiligungsphase.html\" target=\"_blank\">Pressemitteilung<\/a> vom 23.10. hei\u00dft es: &#8222;Nachdem in der Vergangenheit die Planung f\u00fcr einzelne Verkehrsarten und -wege vorwiegend isoliert voneinander stattfand, steht heute eine integrierte <strong>Betrachtung der Mobilit\u00e4tsbed\u00fcrfnisse der Menschen<\/strong> im Vordergrund. Dabei sollen <strong>alle Fortbewegungsarten<\/strong> und Verkehrsbelange mit einbezogen werden \u2013 immer unter dem Leitgedanken, die <strong>Lebensqualit\u00e4t f\u00fcr alle<\/strong> zu verbessern. Der IMEP leitet dabei als strategischer Leitfaden und Entscheidungshilfe Ziele f\u00fcr die Entwicklung einer gesamtst\u00e4dtischen Mobilit\u00e4t ab, von denen aus schlie\u00dflich Konzepte und konkrete Ma\u00dfnahmen f\u00fcr die Zukunft entwickelt werden.&#8220;<\/p>\n\n\n\n<p>Die von der Stadt oben genannten Ziele stimmen uns optimistisch &#8211; insbesondere, weil wir uns als B\u00fcrger*innen auf der Projektseite <a rel=\"noreferrer noopener\" href=\"https:\/\/www.pforzheim-mobil.de\/\" target=\"_blank\"><strong>pforzheim-mobil.de<\/strong><\/a> schon heute einbringen k\u00f6nnen. <br>Nutzt also die Gelegenheit und lasst die Stadt wissen, was euch als Radler*in aktuell am meisten st\u00f6rt &#8211; und wie ihr lieber heute als morgen durch unsere Stadt fahren wollt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stadt Pforzheim m\u00f6chte den Rahmen f\u00fcr die Mobilit\u00e4tsentwicklung der n\u00e4chsten Jahre neu definieren und daf\u00fcr gemeinsam mit einem Fachb\u00fcro f\u00fcr Pforzheim einen sogenannten Integrierten Mobilit\u00e4tsentwicklungsplan (kurz: IMEP) erstellen. In einer Pressemitteilung vom 23.10. hei\u00dft es: &#8222;Nachdem in der Vergangenheit die Planung f\u00fcr einzelne Verkehrsarten und -wege vorwiegend isoliert voneinander stattfand, steht heute eine integrierte [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":366,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[45,44,46,47],"_links":{"self":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/362"}],"collection":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=362"}],"version-history":[{"count":5,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/362\/revisions"}],"predecessor-version":[{"id":370,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/362\/revisions\/370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media\/366"}],"wp:attachment":[{"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fahrradstadt-pforzheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}